{"id":128,"count":1,"description":"","link":"https:\/\/koaladent.com\/fr\/equipment_category\/dental-cone-beam-ct-scan\/","name":"Dental cone beam CT scan","slug":"dental-cone-beam-ct-scan","taxonomy":"equipment_category","parent":0,"meta":[],"acf":[],"_links":{"self":[{"href":"https:\/\/koaladent.com\/fr\/wp-json\/wp\/v2\/equipment_category\/128","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/koaladent.com\/fr\/wp-json\/wp\/v2\/equipment_category"}],"about":[{"href":"https:\/\/koaladent.com\/fr\/wp-json\/wp\/v2\/taxonomies\/equipment_category"}],"wp:post_type":[{"href":"https:\/\/koaladent.com\/fr\/wp-json\/wp\/v2\/dental_equipments?equipment_category=128"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}